 {"id":43400,"date":"2022-10-03T14:25:38","date_gmt":"2022-10-03T12:25:38","guid":{"rendered":"https:\/\/foodandgood.fr\/etablissement\/taller-de-yann\/"},"modified":"2024-06-13T13:56:41","modified_gmt":"2024-06-13T11:56:41","slug":"taller-de-yann","status":"publish","type":"etablissement","link":"https:\/\/foodandgood.fr\/es\/taller-de-yann\/","title":{"rendered":"L'Atelier de Yann"},"excerpt":{"rendered":"","protected":false},"author":13,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"beyondwords_generate_audio":"","beyondwords_integration_method":"","beyondwords_project_id":"","beyondwords_content_id":"","beyondwords_preview_token":"","beyondwords_player_content":"","beyondwords_player_style":"","beyondwords_language_code":"","beyondwords_language_id":"","beyondwords_title_voice_id":"","beyondwords_body_voice_id":"","beyondwords_summary_voice_id":"","beyondwords_error_message":"","beyondwords_disabled":"","beyondwords_delete_content":"","beyondwords_podcast_id":"","beyondwords_hash":"","publish_post_to_speechkit":"","speechkit_hash":"","speechkit_generate_audio":"","speechkit_project_id":"","speechkit_podcast_id":"","speechkit_error_message":"","speechkit_disabled":"","speechkit_access_key":"","speechkit_error":"","speechkit_info":"","speechkit_response":"","speechkit_retries":"","speechkit_status":"","speechkit_updated_at":"","_speechkit_link":"","_speechkit_text":""},"class_list":["post-43400","etablissement","type-etablissement","status-publish","has-post-thumbnail","hentry","type-etablissement-cafeteria-tearoom","type-etablissement-dulce-descanso"],"acf":{"id_eta_scn":"","id_app_foodandgood":"","id_exponum":"","abo":[],"etoile_michelin":[],"titre_presentation":"Un soplo de aire fresco en el centro de la ciudad","presentation":"En Alsacia, los d\u00edas de verano pueden ser muy calurosos: puedes aprovechar un paseo por la ciudad para encontrar un poco de frescura en Yann's Workshop.\n\nLa soleada terraza nos permite vigilar la plaza de la catedral: un punto de vista ideal para observar la vida colmariana.\n\nDependiendo de la hora, pida una ensalada Power Bowl para componer, una bola de helado casera o un c\u00f3ctel con notas de maracuy\u00e1 o fresa.\n\nEl Master Pastry Chef Chocolatier le ofrece durante todo el a\u00f1o \"Pastel de bodas\" y \"Dise\u00f1o de pasteles\", personalizados seg\u00fan sus deseos.\n\nPara las fiestas, descubra muchas ideas de regalos y aproveche la nueva tienda en l\u00ednea para ordenar desde su sof\u00e1!\n\n\u00bfSe avecina un deseo gourmet? \u00a1La Perla de Yuzu o la Nube son los postres que no te puedes perder este verano!","types_prestation":false,"photo":24532,"photo_bis":6410,"photo_3":6413,"adresse":{"address":"L'atelier de Yann, Place de la Cath\u00e9drale, Colmar, France","lat":48.0772203,"lng":7.359015299999998,"zoom":7,"place_id":"ChIJqc2GleZlkUcRLEaU2NBEb0w","name":"L'atelier de Yann","street_number":11,"street_name":"Place de la Cath\u00e9drale","street_name_short":"Pl. de la Cath\u00e9drale","city":"Colmar","state":"Grand Est","post_code":68000,"country":"France","country_short":"FR"},"horaires":"Lunes: Cerrado\nMartes: 09:00 - 18:00\nMi\u00e9rcoles: 09:00 - 18:00\nJueves: 09:00 - 18:00\nViernes: 09:00 - 18:00\nS\u00e1bado: 09:00 - 18:00\nDomingo: Cerrado","tel":"03 89 20 01 00","boutons":[{"title":"Sitio de Internet","link":"http:\/\/www.atelier-de-yann.com\/"},{"title":"Boutique y Hora del T\u00e9","link":"https:\/\/www.atelier-de-yann.com\/copie-de-accueil"}],"boutons_reservation":"","boutons_social":null,"articles":[{"title":"","text":"","image":""}]},"_links":{"self":[{"href":"https:\/\/foodandgood.fr\/es\/wp-json\/wp\/v2\/etablissement\/43400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/foodandgood.fr\/es\/wp-json\/wp\/v2\/etablissement"}],"about":[{"href":"https:\/\/foodandgood.fr\/es\/wp-json\/wp\/v2\/types\/etablissement"}],"author":[{"embeddable":true,"href":"https:\/\/foodandgood.fr\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/foodandgood.fr\/es\/wp-json\/wp\/v2\/comments?post=43400"}],"version-history":[{"count":1,"href":"https:\/\/foodandgood.fr\/es\/wp-json\/wp\/v2\/etablissement\/43400\/revisions"}],"predecessor-version":[{"id":81897,"href":"https:\/\/foodandgood.fr\/es\/wp-json\/wp\/v2\/etablissement\/43400\/revisions\/81897"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/foodandgood.fr\/es\/wp-json\/wp\/v2\/media\/24532"}],"wp:attachment":[{"href":"https:\/\/foodandgood.fr\/es\/wp-json\/wp\/v2\/media?parent=43400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}